{"id":11057,"date":"2023-10-31T08:23:20","date_gmt":"2023-10-31T07:23:20","guid":{"rendered":"https:\/\/chaccoinfo.com\/?p=11057"},"modified":"2023-10-31T08:24:12","modified_gmt":"2023-10-31T07:24:12","slug":"rescatan-a-un-poni-a-punto-de-morir-y-los-perros-de-la-familia-lo-ayudan-a-sobrevivir","status":"publish","type":"post","link":"https:\/\/chaccoinfo.com\/de\/rescatan-a-un-poni-a-punto-de-morir-y-los-perros-de-la-familia-lo-ayudan-a-sobrevivir\/","title":{"rendered":"Rescatan a un poni a punto de morir y los perros de la familia lo ayudan a sobrevivir"},"content":{"rendered":"<h5 class=\"epigraph\" style=\"text-align: center;\"><strong>La actitud del poni cambi\u00f3 por completo cuando comenz\u00f3 a pasar tiempo con los perros<\/strong><\/h5>\n<p class=\"paragraph\" data-gtm-element-container=\"modulo-texto-link\">El peque\u00f1o\u00a0poni\u00a0Tubby tuvo la suerte de ser rescatado por una familia que decidi\u00f3 acogerlo en su hogar hasta que se recuperase, tras ser atacado por tres perros en Granada. Una historia que sucedi\u00f3 hace aproximadamente un a\u00f1o y medio, pero que se est\u00e1 haciendo viral en redes sociales debido al v\u00eddeo que han compartido contando su experiencia. Cuando lo salvaron, Tubby el poni era tan jovencito y se encontraba en un estado tan vulnerable que tuvieron que meterlo dentro de casa con ellos.<\/p>\n<p class=\"paragraph\" data-gtm-element-container=\"modulo-texto-link\">La salud de este animal estaba en detrimento, puesto que contaba con diversos problemas que complicaban su vida. Uno de ellos era la deformidad de su mand\u00edbula, ya que presentaba un caso grave de submordida. As\u00ed como otros problemas de salud que requer\u00edan de atenci\u00f3n veterinaria y de un proceso de recuperaci\u00f3n. Tubby fue rescatado por el R&amp;R Ranch Miniature Horse Sanctuary, un refugio para ponis y caballos en miniatura situado en el Valle de Chesterfield de Misuri, en Estados Unidos. Aunque fueron los perros de la familia, de la raza Golden Retriever, los que ayudaron a que mejorara su salud.<\/p>\n<p data-gtm-element-container=\"modulo-texto-link\">La familia explica en el v\u00eddeo que se ha hecho viral que estaban muy preocupados por Tubby, ya que no estaba muy claro si el peque\u00f1o poni ser\u00eda capaz de sobrevivir o no debido a su estado de salud. El animal se encontraba en una especie de letargo, seg\u00fan explican, no mostraba energ\u00eda. R&amp;R Ranch Miniature Horse Sanctuary tuvo incluso que acondicionar un espacio en la cuadra para mantenerlo en cuarentena. Y parece que el cambio decisivo fue cuando colocaron un enorme peluche de un oso, del que Tubby no se despegaba. Se recostaba sobre \u00e9l y dorm\u00eda junto a este. El siguiente paso fue cuando comenz\u00f3 a entrar en contacto con los Golden Retriever de la familia.<\/p>\n<blockquote class=\"twitter-tweet\" data-width=\"500\" data-dnt=\"true\">\n<p lang=\"en\" dir=\"ltr\">Horse who&#39;s smaller than his golden retriever siblings loves to give them kisses \ud83d\udc9b <a href=\"https:\/\/t.co\/rCKtmT9hUu\">pic.twitter.com\/rCKtmT9hUu<\/a><\/p>\n<p>&mdash; The Dodo (@dodo) <a href=\"https:\/\/twitter.com\/dodo\/status\/1718613663198925228?ref_src=twsrc%5Etfw\" target=\"_blank\" rel=\"noopener\">October 29, 2023<\/a><\/p><\/blockquote>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<p class=\"paragraph\" data-gtm-element-container=\"modulo-texto-link\">Cuando el peque\u00f1o poni empez\u00f3 a pasar tiempo con ellos, su actitud cambi\u00f3, seg\u00fan asegura la familia. \u201cSus ojos empezaron a ser m\u00e1s brillantes\u201d, afirman en el v\u00eddeo. Poco a poco, el animal mejor\u00f3 su salud, pod\u00eda dar paseos por el jard\u00edn, se mostraba m\u00e1s en\u00e9rgico. Y su apetito tambi\u00e9n aument\u00f3. Cada vez era m\u00e1s sociable y disfrutaba jugando con sus compa\u00f1eros Golden Retriever, dando saltos y descansando junto a ellos. Hasta que por fin se convirti\u00f3 en un animal alegre y sano.<\/p>\n<p class=\"paragraph\" data-gtm-element-container=\"modulo-texto-link\">Actualmente, es posible ver v\u00eddeos sobre Tubby publicados en la cuenta oficial de R&amp;R Ranch Miniature Horse Sanctuary. La historia ha conmovido a los internautas, sobre todo en plataformas como X (anteriormente Twitter), en las que el v\u00eddeo del peque\u00f1o poni se est\u00e1 haciendo viral.<\/p>\n<p style=\"text-align: center;\"><strong>Aqu\u00ed pod\u00e9is verlo <a href=\"https:\/\/www.facebook.com\/randrranchminis\/\" target=\"_blank\" rel=\"noopener\">R&amp;R Ranch Minis\u00a0<\/a><\/strong><\/p>\n<p data-gtm-element-container=\"modulo-texto-link\">Fuente: La Vanguardia<\/p>","protected":false},"excerpt":{"rendered":"<p>La actitud del poni cambi\u00f3 por completo cuando comenz\u00f3 a pasar tiempo con los perros El peque\u00f1o\u00a0poni\u00a0Tubby tuvo la suerte [&hellip;]<\/p>\n","protected":false},"author":11,"featured_media":11058,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"_joinchat":[],"footnotes":""},"categories":[1400],"tags":[626,627],"ubicacion-de-banners":[],"class_list":["post-11057","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-poni","tag-tubby"],"_links":{"self":[{"href":"https:\/\/chaccoinfo.com\/de\/wp-json\/wp\/v2\/posts\/11057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/chaccoinfo.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/chaccoinfo.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/chaccoinfo.com\/de\/wp-json\/wp\/v2\/users\/11"}],"replies":[{"embeddable":true,"href":"https:\/\/chaccoinfo.com\/de\/wp-json\/wp\/v2\/comments?post=11057"}],"version-history":[{"count":5,"href":"https:\/\/chaccoinfo.com\/de\/wp-json\/wp\/v2\/posts\/11057\/revisions"}],"predecessor-version":[{"id":11064,"href":"https:\/\/chaccoinfo.com\/de\/wp-json\/wp\/v2\/posts\/11057\/revisions\/11064"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/chaccoinfo.com\/de\/wp-json\/wp\/v2\/media\/11058"}],"wp:attachment":[{"href":"https:\/\/chaccoinfo.com\/de\/wp-json\/wp\/v2\/media?parent=11057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/chaccoinfo.com\/de\/wp-json\/wp\/v2\/categories?post=11057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/chaccoinfo.com\/de\/wp-json\/wp\/v2\/tags?post=11057"},{"taxonomy":"ubicacion-de-banners","embeddable":true,"href":"https:\/\/chaccoinfo.com\/de\/wp-json\/wp\/v2\/ubicacion-de-banners?post=11057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}